{"id":323,"date":"2011-11-24T14:50:08","date_gmt":"2011-11-24T14:50:08","guid":{"rendered":"http:\/\/www.geam.org.py\/v3\/cgp\/?p=250"},"modified":"2011-11-24T14:50:08","modified_gmt":"2011-11-24T14:50:08","slug":"paraguay-integra-la-alianza-de-sociedad-de-gobierno-abierto","status":"publish","type":"post","link":"https:\/\/www.geam.org.py\/v3\/blog\/paraguay-integra-la-alianza-de-sociedad-de-gobierno-abierto\/","title":{"rendered":"Paraguay integra la alianza de Sociedad de Gobierno Abierto"},"content":{"rendered":"<p>La Organizaci\u00f3n OGP (Open Government Partnership) ha reconocido oficialmente la  incorporaci\u00f3n de Paraguay a la Alianza de Sociedad de Gobierno Abierto. La solicitud fue realizada a trav\u00e9s de una nota cursada este mes de noviembre por la Secretar\u00eda T\u00e9cnica de Planificaci\u00f3n del Desarrollo Econ\u00f3mico y Social de la Presidencia de la Rep\u00fablica (STP), en la cual se expresa el compromiso con los principios de un Gobierno Abierto.<!--more--><\/p>\n<p>La STP promovi\u00f3 los esfuerzos necesarios para este objetivo, que responde a la voluntad firme de propiciar un cambio cultural, en los procesos, en las organizaciones y en las formas de relacionamiento con la ciudadan\u00eda, cumpliendo con las exigencias de mayor transparencia y participaci\u00f3n, a fin de que el pa\u00eds se integre al conjunto de Gobiernos m\u00e1s abiertos e interactivos, impulsando las reformas gubernamentales que apuntes a la evoluci\u00f3n del sistema democr\u00e1tico.<\/p>\n<p>Esta alianza significa la uni\u00f3n de Paraguay con otros pa\u00edses del mundo, a fin de promover pol\u00edticas p\u00fablicas m\u00e1s leg\u00edtimas y colaborativas, generando nueva gobernanza democr\u00e1tica, caracterizada por la igualdad, equidad, imparcialidad, honestidad, transparencia, la coherencia, la eficacia, la eficiencia, la apertura a la participaci\u00f3n, la rendici\u00f3n de cuentas y la responsabilidad en la gesti\u00f3n, fundando gobiernos capaces de crear confianza y credibilidad para con la ciudadan\u00eda.<\/p>\n<p>Esta iniciativa es acompa\u00f1ada por el Programa de Democracia &#8220;Calidad en la Gesti\u00f3n P\u00fablica&#8221;, con el apoyo de geAm &#8211; Gesti\u00f3n Ambiental y la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID).<\/p>\n<p><strong>Para mayor informaci\u00f3n: <\/strong>\u00c1rea de Comunicaci\u00f3n &#8211; Tel.: 281 273 int. 125 &#8211; 0991804078 \/ 0982361234 &#8211; <a href=\"..\/..\/..\/\">www.geam.org.py<\/a> &#8211; comunicacion@geam.org.py &#8211; Facebook: <a href=\"http:\/\/www.facebook.com\/pages\/geAm-Gestion-Ambiental\/112535915452254\">geAm \u2013 Gesti\u00f3nAmbiental<\/a> &#8211; Twitter: <a href=\"http:\/\/twitter.com\/#%21\/GEAM_PY\">@geAm_py<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Organizaci\u00f3n OGP (Open Government Partnership) ha reconocido oficialmente la incorporaci\u00f3n de Paraguay a la Alianza de Sociedad de Gobierno Abierto. La solicitud fue realizada a trav\u00e9s de una nota cursada este mes de noviembre por la Secretar\u00eda T\u00e9cnica de Planificaci\u00f3n del Desarrollo Econ\u00f3mico y Social de la Presidencia de la Rep\u00fablica (STP), en la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[51,52],"_links":{"self":[{"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/posts\/323"}],"collection":[{"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/comments?post=323"}],"version-history":[{"count":0,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/posts\/323\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/media?parent=323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/categories?post=323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/tags?post=323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}