{"id":1557,"date":"2013-10-28T13:28:25","date_gmt":"2013-10-28T13:28:25","guid":{"rendered":"http:\/\/www.geam.org.py\/v3\/?p=1557"},"modified":"2013-10-29T13:21:53","modified_gmt":"2013-10-29T13:21:53","slug":"realizan-taller-sobre-modernizacion-del-sector-agua-y-saneamiento","status":"publish","type":"post","link":"https:\/\/www.geam.org.py\/v3\/blog\/realizan-taller-sobre-modernizacion-del-sector-agua-y-saneamiento\/","title":{"rendered":"Realizan taller sobre modernizaci\u00f3n del sector agua y saneamiento"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.geam.org.py\/v3\/uploads\/2013\/10\/PanelAgua-1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-1560\" title=\"PanelAgua (1)\" src=\"http:\/\/www.geam.org.py\/v3\/uploads\/2013\/10\/PanelAgua-1.jpg\" alt=\"\" width=\"435\" height=\"298\" \/><\/a><\/p>\n<p>El viernes 18 de octubre, en el Sal\u00f3n Auditorio del Ministerio de Obras P\u00fablicas y Comunicaciones, se llev\u00f3 a cabo la reuni\u00f3n de la mesa sectorial de Gobernabilidad de Agua Potable y Saneamiento, donde se analizaron temas relacionados al proyecto encarado por el Banco Mundial \u00a0sobre \u201cModernizaci\u00f3n del Sector Agua y Saneamiento\u201d.<\/p>\n<p>En la oportunidad, brindaron una charla Magal\u00ed Gonz\u00e1lez, quien se refiri\u00f3 al Sistema de Informaci\u00f3n Sectorial (SIS), Jorge Abatte quien tuvo a su cargo la ponencia sobre los \u201cLineamientos de Pol\u00edticas de Agua Potable y Saneamiento\u201d y, Luis Sisul quien habl\u00f3 sobre la \u201cPol\u00edtica de agua y Saneamiento para zonas periurbana, rurales y comunidades ind\u00edgenas\u201d.<\/p>\n<p>Acompa\u00f1aron el evento miembros del Comit\u00e9 de Coordinaci\u00f3n General del Sector de Agua, Comisi\u00f3n Nacional de Defensa de los Recursos Naturales \u00a0(Conaderna), Empresa de Servicios Sanitarios del Paraguay (ESSAP), Secretar\u00eda del Ambiente (SEAM), Secretar\u00eda T\u00e9cnica de Planificaci\u00f3n (STP), Servicio Nacional de Saneamiento Ambiental (SENASA) y Municipalidad de Asunci\u00f3n.<\/p>\n<p>Adem\u00e1s estuvieron presentes representantes de organismos de cooperaci\u00f3n internacional, organizaciones no gubernamentales y consultores del \u00e1rea como la C\u00e1mara Paraguaya de Agua (CAPA), Asociaci\u00f3n de Juntas de Saneamiento, Banco Interamericano de Desarrollo (BID), Gesti\u00f3n Ambiental (geAm), Organizaci\u00f3n Paraguaya de Cooperaci\u00f3n Intermunicipal (OPACI), Consejo de Gobernadores, Programa de las Naciones Unidas para el Desarrollo (PNUD), Nipon Koei \u00a0y otras instituciones que est\u00e1n vinculadas a este proyecto dedicado a potenciar la explotaci\u00f3n del sistema de agua potable en el pa\u00eds.<\/p>\n<p>Entre los objetivos generales de la reuni\u00f3n se destac\u00f3 la necesidad de fortalecer a la ciudadan\u00eda para la promoci\u00f3n y protecci\u00f3n de sus derechos, la participaci\u00f3n en la toma de decisiones y el control de las acciones del sector p\u00fablico.<\/p>\n<p>Igualmente coincidieron en que se deber\u00e1 dise\u00f1ar e implementar un esquema de financiamiento de infraestructura a mediano y largo plazo de los servicios de agua potable y mejorar el acceso y la calidad de la prestaci\u00f3n de servicios de agua y saneamiento en zonas rurales y comunidades ind\u00edgenas del interior del pa\u00eds.<\/p>\n<p>En cuanto al sistema de informaci\u00f3n sectorial, se resalt\u00f3 que en el Paraguay, la falta de sistema de informaci\u00f3n bien estructurado en el sector de agua y saneamiento, constituye una importante limitaci\u00f3n para el desarrollo y mejoramiento de la prestaci\u00f3n de servicios de agua potable y alcantarillado sanitario.<\/p>\n<p>A ra\u00edz de esta situaci\u00f3n, surge la necesidad de la definici\u00f3n de un modelo conceptual para un Sistema de Informaci\u00f3n Sectorial (SIS). Este organismo pretende facilitar el acceso a la informaci\u00f3n oportuna sobre entidades, instituciones e indicadores de calidad de los servicios para una mejor planificaci\u00f3n del sector integrando demandas de desarrollo del sector con las distintas fuentes de recursos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 18 de octubre, en el Sal\u00f3n Auditorio del Ministerio de Obras P\u00fablicas y Comunicaciones, se llev\u00f3 a cabo la reuni\u00f3n de la mesa sectorial de Gobernabilidad de Agua Potable y Saneamiento, donde se analizaron temas relacionados al proyecto encarado por el Banco Mundial \u00a0sobre \u201cModernizaci\u00f3n del Sector Agua y Saneamiento\u201d. En la oportunidad, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[55,66],"_links":{"self":[{"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/posts\/1557"}],"collection":[{"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/comments?post=1557"}],"version-history":[{"count":1,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/posts\/1557\/revisions"}],"predecessor-version":[{"id":1559,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/posts\/1557\/revisions\/1559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/media\/1558"}],"wp:attachment":[{"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/media?parent=1557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/categories?post=1557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geam.org.py\/v3\/wp-json\/wp\/v2\/tags?post=1557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}